{"id":1327,"date":"2020-10-01T19:37:31","date_gmt":"2020-10-01T17:37:31","guid":{"rendered":"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/?p=1327"},"modified":"2024-02-04T08:04:29","modified_gmt":"2024-02-04T07:04:29","slug":"warum-klassische-technik-und-saubere-haltung-eine-befreiung-ist","status":"publish","type":"post","link":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/warum-klassische-technik-und-saubere-haltung-eine-befreiung-ist\/","title":{"rendered":"Warum klassische Technik und eine saubere Haltung auf der Gitarre eine Befreiung ist"},"content":{"rendered":"<p>Als Gitarrenlehrer begegne ich immer wieder einer gewissen Skepsis vor einer \u201czu technischen\u201d Sicht auf die Gitarre, als w\u00e4re eine fundierte klassische Spieltechnik ein unn\u00f6tig komplizierter Weg, die Gitarre zu spielen. Dabei st\u00f6sst saubere Technik einfach nur T\u00fcren auf und befreit von mechanischen Problemen. Ob ein Sch\u00fcler am Lagerfeuer schraddeln will, ob es Blues-Improvisation sein soll, ob jemand E-Gitarre in einer Metal-Band spielt: wer seine H\u00e4nde falsch h\u00e4lt, wer unn\u00f6tig weite Bewegungen macht und wer die Spielmuskulatur verspannt, wo keine Spannung n\u00f6tig ist, der hat es schwer. Und genau dies vermeidet man mit einer sauberen klassischen Gitarrentechnik.<\/p>\n<p><!--more--><\/p>\n<p>Die moderne klassische Gitarre ist ein vergleichsweise junges Instrument. Die von Antonio de Torres Mitte des 19. Jahrhunderts perfektionierte Bauweise erm\u00f6glichte und erforderte eine neue Technik, die von Franciso T\u00e1rrega um die Jahrhundertwende revolutioniert und schlie\u00dflich von Andr\u00e9s Segovia (mit einigen Modifikationen) in die Welt getragen wurde. Dadurch, dass der kleine Finger der rechten Hand nicht mehr auf der Gitarrendecke aufgesetzt wurde, bekam diese Hand ganz neue M\u00f6glichkeiten der Klangformung von hartem, lautem Spiel nahe am Steg und weicheren, volleren T\u00f6nen durch Zupfen in der N\u00e4he des Schalloches. Die Klangpalette wurde ausserdem um das Spiel mit ohne Fingern\u00e4gel erweitert, um freien (tirando) und angelegten (apoyando) Anschlag als gleichwertige Optionen. Ziel dieser Technik ist mit m\u00f6glichst effizienten Bewegungen und nie mehr als der n\u00f6tigsten Spannung volle Kontrolle \u00fcber den Ton zu bekommen, und zwar sowohl in der rechten als auch in der linken Hand. Saubere Technik erm\u00f6glicht also nicht nur ein Spiel ohne Anstrengung und ohne Verkrampfen, sondern das, was herauskommt, wenn man nicht mehr nur darum k\u00e4mpft, die richtigen T\u00f6ne in der richtigen Reihenfolge zu spielen: Musik.<\/p>\n<p>Gute Technik beginnt mit der richtigen Haltung und die folgende \u00dcbung zwingt den Fingern die richtige Haltung f\u00f6rmlich auf, sie kann n\u00e4mlich sonst nicht klingen. Achtet darauf, dass jeder Ton so lange klingt, bis auf der Saite der n\u00e4chste Ton gespielt wird; die beiden Notationen klingen exakt gleich, die erste ist aber besser lesbar. Lasst alle 8 T\u00f6ne ohne Absetzen so lange klingen wie ihr k\u00f6nnt. Die Fingerkuppen m\u00fcssen daf\u00fcr im rechten Winkel auf den Hals aufsetzen und nicht von der Seite, der Daumen bleibt am Halsr\u00fccken fixiert, das Handgelenk m\u00f6glichst gerade. Die \u00dcbung f\u00f6rdert nicht nur die richtige Haltung sondern auch die Unabh\u00e4ngigkeit der Finger der linken Hand: der Ringfinger w\u00fcrde sich nur zu gerne mit dem kleinen Finger mitbewegen, muss aber stehenbleiben, um den Ton zu halten.<\/p>\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/wp-content\/uploads\/2020\/09\/Haltung_1_Notenbeispiel-1024x419.png\" alt=\"\" class=\"wp-image-1330\" width=\"690\" height=\"282\" srcset=\"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/wp-content\/uploads\/2020\/09\/Haltung_1_Notenbeispiel-1024x419.png 1024w, https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/wp-content\/uploads\/2020\/09\/Haltung_1_Notenbeispiel-300x123.png 300w, https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/wp-content\/uploads\/2020\/09\/Haltung_1_Notenbeispiel-768x314.png 768w, https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/wp-content\/uploads\/2020\/09\/Haltung_1_Notenbeispiel.png 1397w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/><\/figure>\n\n\n<p>Saubere Technik ist kein Umweg, sondern eine Abk\u00fcrzung, und zwar vollkommen unabh\u00e4ngig davon, was man spielen will. Und je fr\u00fcher man sich beim Erlernen der Gitarre damit auseinandersetzt, umso freier wird man im Spiel.<\/p>\n<p>Nehmt euch zur Kontrolle gern selbst auf, da man genauer hinh\u00f6rt, wenn man nicht selbst spielt. Kuckt dazu in den Blogeintrag \u201c<a href=\"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/selbstkontrolle-beim-ueben-mit-dem-handy-smartphone\/\">Selbstkontrolle beim \u00dcben mit dem Handy\/Smartphone.<\/a>\u201d<\/p>\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Als Gitarrenlehrer begegne ich immer wieder einer gewissen Skepsis vor einer \u201czu technischen\u201d Sicht auf die Gitarre, als w\u00e4re eine fundierte klassische Spieltechnik ein unn\u00f6tig komplizierter Weg, die Gitarre zu spielen. Dabei st\u00f6sst saubere Technik einfach nur T\u00fcren auf und befreit von mechanischen Problemen. Ob ein Sch\u00fcler am Lagerfeuer schraddeln will, ob es Blues-Improvisation sein &hellip; <a href=\"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/warum-klassische-technik-und-saubere-haltung-eine-befreiung-ist\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Warum klassische Technik und eine saubere Haltung auf der Gitarre eine Befreiung ist<\/span><\/a><\/p>","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,3,12],"tags":[75,50,38,80,77,29,40],"class_list":["post-1327","post","type-post","status-publish","format-standard","hentry","category-gitarre-kurs","category-richtig-ueben","category-spieltechnik","tag-gitarre-kurs","tag-gitarre-lernen","tag-haltung-beim-musizieren","tag-musikwoche-fuer-klassische-gitarre","tag-smartphone","tag-spieltechnik","tag-tipps-fuer-anfaenger"],"_links":{"self":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":6,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"predecessor-version":[{"id":1423,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/1327\/revisions\/1423"}],"wp:attachment":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}