{"id":514,"date":"2015-11-15T11:10:55","date_gmt":"2015-11-15T10:10:55","guid":{"rendered":"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/?p=514"},"modified":"2024-02-04T08:26:18","modified_gmt":"2024-02-04T07:26:18","slug":"lagenspiel-und-immerwaehrendes-vibrato-oder-sollte-man-leere-saiten-beim-geigenspiel-tunlichst-vermeiden","status":"publish","type":"post","link":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/lagenspiel-und-immerwaehrendes-vibrato-oder-sollte-man-leere-saiten-beim-geigenspiel-tunlichst-vermeiden\/","title":{"rendered":"Lagenspiel und immerw\u00e4hrendes Vibrato. Oder: sollte man leere Saiten beim Geigenspiel tunlichst vermeiden?"},"content":{"rendered":"<p>Ger\u00fcchteweise existieren sie noch, die Apologeten der fr\u00f6hlichen Beisl- bzw. Kneipengastronomie, die nicht nur Koriander, Kreuzk\u00fcmmel , Oliven oder B\u00fcffelmozarella, sonder gar jegliches unpanierte Gem\u00fcse meiden wie der Teufel das Weihwasser. Ganz \u00e4hnlichen Reflexen begegnet man gelegentlich auch bei Vertretern der Geigenzunft. So werden beispielsweise gar nicht selten heftige Intoleranzen gegen\u00fcber leeren Saiten gehegt, einer ganz und gar nicht geschmacklosen Zutat des Klangspektrums von Streichinstrumenten.<\/p>\n<p>Das Dogma, leere Saiten tunlichst zu vermeiden, l\u00e4sst sich als nicht mehr ganz zeitgem\u00e4\u00dfe Ansicht innerhalb einer wechselvollen Geschichte verorten, in der sich der Instrumentenbau, Klangvorstellungen, Spieltechniken und damit auch die Pr\u00e4ferenzen f\u00fcr Fingers\u00e4tze ebenso stark wandelten, wie die Musikstile und Kompositionen, in deren Diensten sie standen.<br \/>\n<!--more--><\/p>\n<h2>Barock und Romantik<\/h2>\n<p>Zur Zeit des Barock wurde der offene Klang von leeren Saiten wohl als Zierde wahrgenommen. <a href=\"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wie-spielt-man-auf-der-geige-in-den-lagen\/\" title=\"Wie spielt man auf der Geige in den Lagen?\">Lagenspiel<\/a> schien vor allem an Passagen zweckm\u00e4\u00dfig, an denen die T\u00f6ne von der ersten Lage aus nicht mehr erreicht werden konnten. Das Vibrato wurde vermutlich sparsam verwendet. In Lehrwerken des 17. und 18. Jahrhunderts wird es unter der Rubrik &#8222;Verzierungen&#8220;, also im gleichen Atemzug wie Vorschlag, Doppelschlag, Pralltriller etc. abgehandelt, was auf einen sehr gezielten Gebrauch hinweist. Mit Sicherheit klangen die leeren Saiten auf den alten Geigen (u.a. h\u00e4ufig eine flachere Halsneigung, k\u00fcrzere Spielmensur) durch die Verwendung von Darmsaiten vergleichsweise weich.<\/p>\n<p>Im 19. Jahrhundert \u00e4nderte sich die Geigentechnik grundlegend. Die Konzerts\u00e4le wurden ger\u00e4umiger, die Saiten wurden straffer gespannt und der moderne Geigenbogen, der permanenten Druck auf langen T\u00f6nen beg\u00fcnstigt, setzte sich durch. Das h\u00e4ufige Spiel in h\u00f6heren Lagen hat sich &#8212; nicht zuletzt durch den Einfuss des Virtuosentums &#8212; l\u00e4ngst vom Sonderfall zur geigerischen Kernkompetenz entwickelt. Insbesondere h\u00e4ufige Lagenwechsel &#8212; Beriots Volinschule l\u00e4sst etwa darauf schlie\u00dfen, dass das sogenannte Portamento (ein h\u00f6rbarer Schleifer) viel wichtiger war als das Vibrato &#8212; avancierten zum Ausdrucksmittel.<\/p>\n<h2>Das 20. Jahrhundert und die Vermarktung des Br\u00fchw\u00fcrfels<\/h2>\n<p>Im ersten Drittel des 20. Jahrhunderts gelangten Geigensaiten mit Stahlkernen auf den Markt. Etwa gleichzeitig kommt nicht nur Maggis Suppenw\u00fcrfe schwer in Mode, sondern auch das permanente Vibratospiel wird auf der Geige als klangliche Allzweckwaffe entdeckt. Allein aus diesem Grund schien die Verwendung von leeren Saiten als nicht mehr opportun und wurde nur noch dort akzeptiert, wo sich technisch so gut wie keine sinnvollen Alternativen anboten.<\/p>\n<h2>Zeitgem\u00e4\u00dfe Persepektiven<\/h2>\n<p>Bis heute haben sich die klanglichen Anschauungen eindeutig ge\u00e4ndert, was nicht zuletzt der historisch informierten Auff\u00fchrungspraxis geschuldet ist. Ab den 60er Jahren wurden auf der Suche nach den alten Methoden nicht nur Aspekte des historischen Instrumentenbaus wiederbelebt, sondern auch Spieltechniken und andere musikalische Belange adaptiert. Speziell in Bezug auf die Barockmusik besann man sich auf ein eindeutig schlankeres und transparenteres Klangbild &#8212; auf den sparsamen und differenzierten Einsatz des Vibratos, seltenes Lagenspiel und nicht zuletzt auch auf die ungenierte Verwendung von leeren Saiten. In j\u00fcngerer Zeit wurde diese vermeintliche oder tats\u00e4chliche historische Pr\u00e4zision auch im Hinblick auf andere Epochen popul\u00e4r. So h\u00f6rt man heute nicht selten sogar romantische Werke, etwa Brahms&#8216; Sonaten, im schlanken Ton auf weichen Darmsaiten, partnerschaftich begeitet auf einem historischen Pianforte. Neben den immerw\u00e4hrenden Aspekte der Griff- und Bogentechnik, der Phrasengestaltung und dem Klang, geht der Trend seit einigen Jahrzehnten eindeutig dahin, Entscheidungen bez\u00fcglich der Frage, ob Lagenspiel oder leere Saite, ob sattes Vibrato oder schlanker Ton, st\u00e4rker im Hinblick auf die Epoche des Musikst\u00fcckes zu treffen.<\/p>\n<p>Wer \u00fcbrigens das Gef\u00fchl hat, leere Saiten klingen scharf (bei langen T\u00f6nen auf der E-Saite wird dies meistens der Fall und kaum zu verhindern sein), dem k\u00f6nnte ein anderes Setup des Instruments helfen. M\u00f6glichkeiten sind in erster Linie die Auswahl von weicher klingenden Saiten oder das Einrichten von <a href=\"http:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wie-stellt-man-einen-steg-auf-anleitung-fuer-geige-bratsche-cello-und-kontrabass\/\" title=\"Wie stellt man einen Steg auf? Anleitung f\u00fcr Geige, Bratsche, Cello und Kontrabass\">Steg<\/a> und Stimmstock durch einen Geigenbauer. Bei meiner Geige hat der Geigenbauer \u00fcbrigens ein St\u00fcck Pergament unter die A-Saite auf den Steg geklebt, seitdem klingt die leere Saite attraktiver.  <\/p>","protected":false},"excerpt":{"rendered":"<p>Ger\u00fcchteweise existieren sie noch, die Apologeten der fr\u00f6hlichen Beisl- bzw. Kneipengastronomie, die nicht nur Koriander, Kreuzk\u00fcmmel , Oliven oder B\u00fcffelmozarella, sonder gar jegliches unpanierte Gem\u00fcse meiden wie der Teufel das Weihwasser. Ganz \u00e4hnlichen Reflexen begegnet man gelegentlich auch bei Vertretern der Geigenzunft. So werden beispielsweise gar nicht selten heftige Intoleranzen gegen\u00fcber leeren Saiten gehegt, einer &hellip; <a href=\"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/lagenspiel-und-immerwaehrendes-vibrato-oder-sollte-man-leere-saiten-beim-geigenspiel-tunlichst-vermeiden\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Lagenspiel und immerw\u00e4hrendes Vibrato. Oder: sollte man leere Saiten beim Geigenspiel tunlichst vermeiden?<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,112,12],"tags":[47,20,15,16,19,43,29,14],"class_list":["post-514","post","type-post","status-publish","format-standard","hentry","category-bratsche-kurs","category-geige-kurs","category-spieltechnik","tag-fingersaetze","tag-klang","tag-lagenspiel","tag-lagenwechsel","tag-leere-saite","tag-musiktheorie","tag-spieltechnik","tag-vibrato"],"_links":{"self":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":15,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"predecessor-version":[{"id":1159,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/posts\/514\/revisions\/1159"}],"wp:attachment":[{"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.musikwoche-gruenbach.at\/1000tipps\/en\/wp-json\/wp\/v2\/tags?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}